{"id":136,"name":"lori","url":"http:\/\/www.lifewearfactory.com","description":"","link":"http:\/\/www.ongnau.com\/blog\/author\/lori\/","slug":"lori","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/21603cedb0f0343c5a2ff80452cad7afd5e9b671b38ef796bed0056426f599c4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/21603cedb0f0343c5a2ff80452cad7afd5e9b671b38ef796bed0056426f599c4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/21603cedb0f0343c5a2ff80452cad7afd5e9b671b38ef796bed0056426f599c4?s=96&d=mm&r=g"},"meta":[],"_links":{"self":[{"href":"http:\/\/www.ongnau.com\/blog\/wp-json\/wp\/v2\/users\/136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.ongnau.com\/blog\/wp-json\/wp\/v2\/users"}]}}